{"id":56934,"date":"2026-01-20T12:51:55","date_gmt":"2026-01-20T11:51:55","guid":{"rendered":"https:\/\/sparkoh.be\/?post_type=tribe_events&#038;p=56934"},"modified":"2026-01-20T12:51:55","modified_gmt":"2026-01-20T11:51:55","slug":"ouverture-2237","status":"publish","type":"tribe_events","link":"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/","title":{"rendered":"Ouverture"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"tags":[],"tribe_events_cat":[360],"class_list":["post-56934","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-opening-hours-en","cat_opening-hours-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Opening hours &#8226; SPARKOH!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ouverture\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/\" \/>\n<meta property=\"og:site_name\" content=\"SPARKOH!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SparkohBE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sparkoh_be\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/opening-hours\\\/ouverture-2237\\\/\",\"url\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/opening-hours\\\/ouverture-2237\\\/\",\"name\":\"Opening hours &#8226; SPARKOH!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/#website\"},\"datePublished\":\"2026-01-20T11:51:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/opening-hours\\\/ouverture-2237\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sparkoh.be\\\/en\\\/opening-hours\\\/ouverture-2237\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/opening-hours\\\/ouverture-2237\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opening Hours\",\"item\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/opening-hours\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ouverture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/\",\"name\":\"SPARKOH!\",\"description\":\"Vivez des &eacute;motions scientifiquement prouv&eacute;es\",\"publisher\":{\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/#organization\",\"name\":\"SPARKOH!\",\"url\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sparkoh.be\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/logo-inverse.jpg\",\"contentUrl\":\"https:\\\/\\\/sparkoh.be\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/logo-inverse.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"SPARKOH!\"},\"image\":{\"@id\":\"https:\\\/\\\/sparkoh.be\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SparkohBE\",\"https:\\\/\\\/x.com\\\/Sparkoh_be\",\"https:\\\/\\\/www.instagram.com\\\/sparkoh_BE\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sparkoh\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6JbdX33I9VvnOyfgrgXdvw\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Opening hours &#8226; SPARKOH!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/","og_locale":"en_US","og_type":"article","og_title":"Ouverture","og_url":"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/","og_site_name":"SPARKOH!","article_publisher":"https:\/\/www.facebook.com\/SparkohBE","twitter_card":"summary_large_image","twitter_site":"@Sparkoh_be","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/","url":"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/","name":"Opening hours &#8226; SPARKOH!","isPartOf":{"@id":"https:\/\/sparkoh.be\/en\/#website"},"datePublished":"2026-01-20T11:51:55+00:00","breadcrumb":{"@id":"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sparkoh.be\/en\/opening-hours\/ouverture-2237\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sparkoh.be\/en\/"},{"@type":"ListItem","position":2,"name":"Opening Hours","item":"https:\/\/sparkoh.be\/en\/opening-hours\/"},{"@type":"ListItem","position":3,"name":"Ouverture"}]},{"@type":"WebSite","@id":"https:\/\/sparkoh.be\/en\/#website","url":"https:\/\/sparkoh.be\/en\/","name":"SPARKOH!","description":"Vivez des &eacute;motions scientifiquement prouv&eacute;es","publisher":{"@id":"https:\/\/sparkoh.be\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sparkoh.be\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sparkoh.be\/en\/#organization","name":"SPARKOH!","url":"https:\/\/sparkoh.be\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sparkoh.be\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sparkoh.be\/wp-content\/uploads\/2018\/04\/logo-inverse.jpg","contentUrl":"https:\/\/sparkoh.be\/wp-content\/uploads\/2018\/04\/logo-inverse.jpg","width":1024,"height":1024,"caption":"SPARKOH!"},"image":{"@id":"https:\/\/sparkoh.be\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SparkohBE","https:\/\/x.com\/Sparkoh_be","https:\/\/www.instagram.com\/sparkoh_BE\/","https:\/\/www.linkedin.com\/company\/sparkoh\/","https:\/\/www.youtube.com\/channel\/UC6JbdX33I9VvnOyfgrgXdvw"]}]}},"_links":{"self":[{"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/tribe_events\/56934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/tribe_events\/56934\/revisions"}],"predecessor-version":[{"id":56940,"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/tribe_events\/56934\/revisions\/56940"}],"wp:attachment":[{"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/media?parent=56934"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/tags?post=56934"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/sparkoh.be\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=56934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}